{"id":4920,"date":"2023-07-18T16:54:14","date_gmt":"2023-07-18T20:54:14","guid":{"rendered":"https:\/\/marinedelivers.com\/?page_id=4920"},"modified":"2026-08-13T16:25:31","modified_gmt":"2026-08-13T20:25:31","slug":"nos-membres","status":"publish","type":"page","link":"https:\/\/marinedelivers.com\/fr\/nos-membres\/","title":{"rendered":"Nos membres"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Fond\u00e9e en 1959, la Chambre de commerce maritime relie la communaut\u00e9 maritime depuis lors.<\/h3>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/marinedelivers.com\/fr\/devenezmembre\/\" target=\"_blank\" rel=\"noreferrer noopener\">Vous souhaitez vous joindre \u00e0 nos rangs?<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n<div id=\"entries-block_5c3e8240c5d09f44948622a4f2107ab7\" class=\"entries block\">\n    <form class=\"entries-filter onScroll\">\n            <nav class=\"filters\">\n            <p>Filtrer par<\/p>\n            <ul>\n                                                    <li class=\"filter\">\n                        <button\n                            type=\"button\"\n                            data-filter\n                            data-term=\"108\"\n                            data-cat=\"industry\"\n                            class=\"active\">\n                            Armateurs                        <\/button>\n                    <\/li>\n                                    <li class=\"filter\">\n                        <button\n                            type=\"button\"\n                            data-filter\n                            data-term=\"109\"\n                            data-cat=\"industry\"\n                            >\n                            Entreprises de soutien                        <\/button>\n                    <\/li>\n                                    <li class=\"filter\">\n                        <button\n                            type=\"button\"\n                            data-filter\n                            data-term=\"120\"\n                            data-cat=\"industry\"\n                            >\n                            \u00c9tablissements d&#039;enseignement                        <\/button>\n                    <\/li>\n                                    <li class=\"filter\">\n                        <button\n                            type=\"button\"\n                            data-filter\n                            data-term=\"106\"\n                            data-cat=\"industry\"\n                            >\n                            Exp\u00e9diteurs de marchandises                        <\/button>\n                    <\/li>\n                                    <li class=\"filter\">\n                        <button\n                            type=\"button\"\n                            data-filter\n                            data-term=\"104\"\n                            data-cat=\"industry\"\n                            >\n                            La Voie maritime                        <\/button>\n                    <\/li>\n                                    <li class=\"filter\">\n                        <button\n                            type=\"button\"\n                            data-filter\n                            data-term=\"105\"\n                            data-cat=\"industry\"\n                            >\n                            Ports et collectivit\u00e9s                        <\/button>\n                    <\/li>\n                                    <li class=\"filter\">\n                        <button\n                            type=\"button\"\n                            data-filter\n                            data-term=\"110\"\n                            data-cat=\"industry\"\n                            >\n                            Terminaux                        <\/button>\n                    <\/li>\n                            <\/ul>\n        <\/nav>\n    \n    \n    <\/form>\n    <div class=\"entries-ajax\" data-query='{\"post_type\":[\"member\"],\"posts_per_page\":\"24\",\"post__not_in\":[4920],\"orderby\":\"title\",\"order\":\"ASC\"}' data-columns='4'>\n        \n<div class=\"row\">\n                <div class=\"col-md-6 col-lg-3 mb-5\">\n                <article class=\"member onScroll\">\n    <div class=\"member-asset\">\n        <div class=\"member-asset-inner\">\n            <a href=\"http:\/\/www.algonet.com\" target=\"_blank\" class=\"member-link\">                <img loading=\"lazy\" decoding=\"async\" width=\"305\" height=\"306\" src=\"https:\/\/marinedelivers.com\/wp-content\/uploads\/2023\/08\/Algoma-Central-Corporation-logo.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/marinedelivers.com\/wp-content\/uploads\/2023\/08\/Algoma-Central-Corporation-logo.jpg 305w, https:\/\/marinedelivers.com\/wp-content\/uploads\/2023\/08\/Algoma-Central-Corporation-logo-300x300.jpg 300w, https:\/\/marinedelivers.com\/wp-content\/uploads\/2023\/08\/Algoma-Central-Corporation-logo-150x150.jpg 150w\" sizes=\"auto, (max-width: 305px) 100vw, 305px\" \/>\n            <\/a>        <\/div>\n    <\/div>\n<\/article>            <\/div>\n                    <div class=\"col-md-6 col-lg-3 mb-5\">\n                <article class=\"member onScroll\">\n    <div class=\"member-asset\">\n        <div class=\"member-asset-inner\">\n            <a href=\"https:\/\/www.cslships.com\/en\" target=\"_blank\" class=\"member-link\">                <img loading=\"lazy\" decoding=\"async\" width=\"396\" height=\"81\" src=\"https:\/\/marinedelivers.com\/wp-content\/uploads\/2023\/08\/CSL-Group.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/marinedelivers.com\/wp-content\/uploads\/2023\/08\/CSL-Group.png 396w, https:\/\/marinedelivers.com\/wp-content\/uploads\/2023\/08\/CSL-Group-300x61.png 300w\" sizes=\"auto, (max-width: 396px) 100vw, 396px\" \/>\n            <\/a>        <\/div>\n    <\/div>\n<\/article>            <\/div>\n                    <div class=\"col-md-6 col-lg-3 mb-5\">\n                <article class=\"member onScroll\">\n    <div class=\"member-asset\">\n        <div class=\"member-asset-inner\">\n            <a href=\"http:\/\/www.groupedesgagnes.com\" target=\"_blank\" class=\"member-link\">                <img loading=\"lazy\" decoding=\"async\" width=\"337\" height=\"213\" src=\"https:\/\/marinedelivers.com\/wp-content\/uploads\/2023\/08\/Groupe-Desgagnes.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/marinedelivers.com\/wp-content\/uploads\/2023\/08\/Groupe-Desgagnes.png 337w, https:\/\/marinedelivers.com\/wp-content\/uploads\/2023\/08\/Groupe-Desgagnes-300x190.png 300w\" sizes=\"auto, (max-width: 337px) 100vw, 337px\" \/>\n            <\/a>        <\/div>\n    <\/div>\n<\/article>            <\/div>\n                    <div class=\"col-md-6 col-lg-3 mb-5\">\n                <article class=\"member onScroll\">\n    <div class=\"member-asset\">\n        <div class=\"member-asset-inner\">\n            <a href=\"http:\/\/www.mcasphalt.com\" target=\"_blank\" class=\"member-link\">                <img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"1265\" src=\"https:\/\/marinedelivers.com\/wp-content\/uploads\/2023\/08\/MMTL-Corporate-White-background.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/marinedelivers.com\/wp-content\/uploads\/2023\/08\/MMTL-Corporate-White-background.png 1500w, https:\/\/marinedelivers.com\/wp-content\/uploads\/2023\/08\/MMTL-Corporate-White-background-300x253.png 300w, https:\/\/marinedelivers.com\/wp-content\/uploads\/2023\/08\/MMTL-Corporate-White-background-1024x864.png 1024w, https:\/\/marinedelivers.com\/wp-content\/uploads\/2023\/08\/MMTL-Corporate-White-background-768x648.png 768w\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" \/>\n            <\/a>        <\/div>\n    <\/div>\n<\/article>            <\/div>\n                    <div class=\"col-md-6 col-lg-3 mb-5\">\n                <article class=\"member onScroll\">\n    <div class=\"member-asset\">\n        <div class=\"member-asset-inner\">\n            <a href=\"https:\/\/mckeil.com\" target=\"_blank\" class=\"member-link\">                <img loading=\"lazy\" decoding=\"async\" width=\"2498\" height=\"1490\" src=\"https:\/\/marinedelivers.com\/wp-content\/uploads\/2023\/08\/McKeil_Logo_CMYK_Primary_Colour.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/marinedelivers.com\/wp-content\/uploads\/2023\/08\/McKeil_Logo_CMYK_Primary_Colour.jpg 2498w, https:\/\/marinedelivers.com\/wp-content\/uploads\/2023\/08\/McKeil_Logo_CMYK_Primary_Colour-300x179.jpg 300w, https:\/\/marinedelivers.com\/wp-content\/uploads\/2023\/08\/McKeil_Logo_CMYK_Primary_Colour-1024x611.jpg 1024w, https:\/\/marinedelivers.com\/wp-content\/uploads\/2023\/08\/McKeil_Logo_CMYK_Primary_Colour-768x458.jpg 768w, https:\/\/marinedelivers.com\/wp-content\/uploads\/2023\/08\/McKeil_Logo_CMYK_Primary_Colour-1536x916.jpg 1536w, https:\/\/marinedelivers.com\/wp-content\/uploads\/2023\/08\/McKeil_Logo_CMYK_Primary_Colour-2048x1222.jpg 2048w\" sizes=\"auto, (max-width: 2498px) 100vw, 2498px\" \/>\n            <\/a>        <\/div>\n    <\/div>\n<\/article>            <\/div>\n                    <div class=\"col-md-6 col-lg-3 mb-5\">\n                <article class=\"member onScroll\">\n    <div class=\"member-asset\">\n        <div class=\"member-asset-inner\">\n            <a href=\"https:\/\/www.groupocean.com\" target=\"_blank\" class=\"member-link\">                <img loading=\"lazy\" decoding=\"async\" width=\"337\" height=\"89\" src=\"https:\/\/marinedelivers.com\/wp-content\/uploads\/2023\/08\/Groupe-Ocean.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/marinedelivers.com\/wp-content\/uploads\/2023\/08\/Groupe-Ocean.png 337w, https:\/\/marinedelivers.com\/wp-content\/uploads\/2023\/08\/Groupe-Ocean-300x79.png 300w\" sizes=\"auto, (max-width: 337px) 100vw, 337px\" \/>\n            <\/a>        <\/div>\n    <\/div>\n<\/article>            <\/div>\n                    <div class=\"col-md-6 col-lg-3 mb-5\">\n                <article class=\"member onScroll\">\n    <div class=\"member-asset\">\n        <div class=\"member-asset-inner\">\n            <a href=\"https:\/\/www.oceanex.com\/\" target=\"_blank\" class=\"member-link\">                <img loading=\"lazy\" decoding=\"async\" width=\"836\" height=\"548\" src=\"https:\/\/marinedelivers.com\/wp-content\/uploads\/2025\/04\/Oceanex-Logo.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Oceanex\" srcset=\"https:\/\/marinedelivers.com\/wp-content\/uploads\/2025\/04\/Oceanex-Logo.png 836w, https:\/\/marinedelivers.com\/wp-content\/uploads\/2025\/04\/Oceanex-Logo-300x197.png 300w, https:\/\/marinedelivers.com\/wp-content\/uploads\/2025\/04\/Oceanex-Logo-768x503.png 768w\" sizes=\"auto, (max-width: 836px) 100vw, 836px\" \/>\n            <\/a>        <\/div>\n    <\/div>\n<\/article>            <\/div>\n                    <div class=\"col-md-6 col-lg-3 mb-5\">\n                <article class=\"member onScroll\">\n    <div class=\"member-asset\">\n        <div class=\"member-asset-inner\">\n            <a href=\"http:\/\/www.purvismarine.com\" target=\"_blank\" class=\"member-link\">                <img loading=\"lazy\" decoding=\"async\" width=\"446\" height=\"150\" src=\"https:\/\/marinedelivers.com\/wp-content\/uploads\/2023\/08\/Purvis-Marine-Ltd.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/marinedelivers.com\/wp-content\/uploads\/2023\/08\/Purvis-Marine-Ltd.png 446w, https:\/\/marinedelivers.com\/wp-content\/uploads\/2023\/08\/Purvis-Marine-Ltd-300x101.png 300w\" sizes=\"auto, (max-width: 446px) 100vw, 446px\" \/>\n            <\/a>        <\/div>\n    <\/div>\n<\/article>            <\/div>\n                    <div class=\"col-md-6 col-lg-3 mb-5\">\n                <article class=\"member onScroll\">\n    <div class=\"member-asset\">\n        <div class=\"member-asset-inner\">\n            <a href=\"http:\/\/www.sterlingfuels.ca\" target=\"_blank\" class=\"member-link\">                <img loading=\"lazy\" decoding=\"async\" width=\"299\" height=\"165\" src=\"https:\/\/marinedelivers.com\/wp-content\/uploads\/2023\/08\/Sterling-Fuels-Ltd.-e1551650334549.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" \/>\n            <\/a>        <\/div>\n    <\/div>\n<\/article>            <\/div>\n        <\/div>\n\n    <\/div>\n    <\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Affiliations et partenaires strat\u00e9giques<\/h3>\n\n\n<div id=\"entries-block_ba18460cd2e7ca723322af0eb66052e6\" class=\"entries block\">\n    <form class=\"entries-filter onScroll\">\n            <nav class=\"filters\">\n            <p>Filtrer par<\/p>\n            <ul>\n                                                    <li class=\"filter\">\n                        <button\n                            type=\"button\"\n                            data-filter\n                            data-term=\"130\"\n                            data-cat=\"type\"\n                            class=\"active\">\n                            Affiliations                        <\/button>\n                    <\/li>\n                                    <li class=\"filter\">\n                        <button\n                            type=\"button\"\n                            data-filter\n                            data-term=\"131\"\n                            data-cat=\"type\"\n                            >\n                            Partenaires strat\u00e9giques                        <\/button>\n                    <\/li>\n                            <\/ul>\n        <\/nav>\n    \n    \n    <\/form>\n    <div class=\"entries-ajax\" data-query='{\"post_type\":[\"member\"],\"posts_per_page\":\"24\",\"post__not_in\":[4920],\"orderby\":\"title\",\"order\":\"ASC\"}' data-columns='4'>\n        \n<div class=\"row\">\n                <div class=\"col-md-6 col-lg-3 mb-5\">\n                <article class=\"member onScroll\">\n    <div class=\"member-asset\">\n        <div class=\"member-asset-inner\">\n            <a href=\"https:\/\/www.americancoalcouncil.org\/\" target=\"_blank\" class=\"member-link\">                <img loading=\"lazy\" decoding=\"async\" width=\"597\" height=\"135\" src=\"https:\/\/marinedelivers.com\/wp-content\/uploads\/2026\/07\/American-Coal-Council-Logo.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/marinedelivers.com\/wp-content\/uploads\/2026\/07\/American-Coal-Council-Logo.png 597w, https:\/\/marinedelivers.com\/wp-content\/uploads\/2026\/07\/American-Coal-Council-Logo-300x68.png 300w\" sizes=\"auto, (max-width: 597px) 100vw, 597px\" \/>\n            <\/a>        <\/div>\n    <\/div>\n<\/article>            <\/div>\n                    <div class=\"col-md-6 col-lg-3 mb-5\">\n                <article class=\"member onScroll\">\n    <div class=\"member-asset\">\n        <div class=\"member-asset-inner\">\n            <a href=\"https:\/\/calgarychamber.com\/\" target=\"_blank\" class=\"member-link\">                <img loading=\"lazy\" decoding=\"async\" width=\"808\" height=\"280\" src=\"https:\/\/marinedelivers.com\/wp-content\/uploads\/2026\/06\/Calgary-Chamber-of-Commerce-Logo.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/marinedelivers.com\/wp-content\/uploads\/2026\/06\/Calgary-Chamber-of-Commerce-Logo.png 808w, https:\/\/marinedelivers.com\/wp-content\/uploads\/2026\/06\/Calgary-Chamber-of-Commerce-Logo-300x104.png 300w, https:\/\/marinedelivers.com\/wp-content\/uploads\/2026\/06\/Calgary-Chamber-of-Commerce-Logo-768x266.png 768w\" sizes=\"auto, (max-width: 808px) 100vw, 808px\" \/>\n            <\/a>        <\/div>\n    <\/div>\n<\/article>            <\/div>\n                    <div class=\"col-md-6 col-lg-3 mb-5\">\n                <article class=\"member onScroll\">\n    <div class=\"member-asset\">\n        <div class=\"member-asset-inner\">\n            <a href=\"https:\/\/chamber.ca\/fr\/\" target=\"_blank\" class=\"member-link\">                <img loading=\"lazy\" decoding=\"async\" width=\"988\" height=\"254\" src=\"https:\/\/marinedelivers.com\/wp-content\/uploads\/2026\/06\/Canadian-Chamber-of-Commerce-Logo.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/marinedelivers.com\/wp-content\/uploads\/2026\/06\/Canadian-Chamber-of-Commerce-Logo.png 988w, https:\/\/marinedelivers.com\/wp-content\/uploads\/2026\/06\/Canadian-Chamber-of-Commerce-Logo-300x77.png 300w, https:\/\/marinedelivers.com\/wp-content\/uploads\/2026\/06\/Canadian-Chamber-of-Commerce-Logo-768x197.png 768w\" sizes=\"auto, (max-width: 988px) 100vw, 988px\" \/>\n            <\/a>        <\/div>\n    <\/div>\n<\/article>            <\/div>\n                    <div class=\"col-md-6 col-lg-3 mb-5\">\n                <article class=\"member onScroll\">\n    <div class=\"member-asset\">\n        <div class=\"member-asset-inner\">\n            <a href=\"https:\/\/duluthchamber.com\/\" target=\"_blank\" class=\"member-link\">                <img loading=\"lazy\" decoding=\"async\" width=\"335\" height=\"85\" src=\"https:\/\/marinedelivers.com\/wp-content\/uploads\/2026\/06\/Duluth-Chamber-of-Commerce.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/marinedelivers.com\/wp-content\/uploads\/2026\/06\/Duluth-Chamber-of-Commerce.png 335w, https:\/\/marinedelivers.com\/wp-content\/uploads\/2026\/06\/Duluth-Chamber-of-Commerce-300x76.png 300w\" sizes=\"auto, (max-width: 335px) 100vw, 335px\" \/>\n            <\/a>        <\/div>\n    <\/div>\n<\/article>            <\/div>\n                    <div class=\"col-md-6 col-lg-3 mb-5\">\n                <article class=\"member onScroll\">\n    <div class=\"member-asset\">\n        <div class=\"member-asset-inner\">\n            <a href=\"https:\/\/www.ssmcoc.com\/\" target=\"_blank\" class=\"member-link\">                <img loading=\"lazy\" decoding=\"async\" width=\"566\" height=\"353\" src=\"https:\/\/marinedelivers.com\/wp-content\/uploads\/2026\/08\/Sault-Ste.-Marie-Chamber-of-Commerce-Logo.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/marinedelivers.com\/wp-content\/uploads\/2026\/08\/Sault-Ste.-Marie-Chamber-of-Commerce-Logo.jpg 566w, https:\/\/marinedelivers.com\/wp-content\/uploads\/2026\/08\/Sault-Ste.-Marie-Chamber-of-Commerce-Logo-300x187.jpg 300w\" sizes=\"auto, (max-width: 566px) 100vw, 566px\" \/>\n            <\/a>        <\/div>\n    <\/div>\n<\/article>            <\/div>\n                    <div class=\"col-md-6 col-lg-3 mb-5\">\n                <article class=\"member onScroll\">\n    <div class=\"member-asset\">\n        <div class=\"member-asset-inner\">\n            <a href=\"https:\/\/tbchamber.ca\/\" target=\"_blank\" class=\"member-link\">                <img loading=\"lazy\" decoding=\"async\" width=\"217\" height=\"82\" src=\"https:\/\/marinedelivers.com\/wp-content\/uploads\/2026\/08\/Thunder-Bay-Chamber-of-Commerce-Logo.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" \/>\n            <\/a>        <\/div>\n    <\/div>\n<\/article>            <\/div>\n                    <div class=\"col-md-6 col-lg-3 mb-5\">\n                <article class=\"member onScroll\">\n    <div class=\"member-asset\">\n        <div class=\"member-asset-inner\">\n            <a href=\"https:\/\/www.uschamber.com\/\" target=\"_blank\" class=\"member-link\">                <img loading=\"lazy\" decoding=\"async\" width=\"1124\" height=\"258\" src=\"https:\/\/marinedelivers.com\/wp-content\/uploads\/2026\/06\/U.S.-Chamber-of-Commerce-Logo.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/marinedelivers.com\/wp-content\/uploads\/2026\/06\/U.S.-Chamber-of-Commerce-Logo.png 1124w, https:\/\/marinedelivers.com\/wp-content\/uploads\/2026\/06\/U.S.-Chamber-of-Commerce-Logo-300x69.png 300w, https:\/\/marinedelivers.com\/wp-content\/uploads\/2026\/06\/U.S.-Chamber-of-Commerce-Logo-1024x235.png 1024w, https:\/\/marinedelivers.com\/wp-content\/uploads\/2026\/06\/U.S.-Chamber-of-Commerce-Logo-768x176.png 768w\" sizes=\"auto, (max-width: 1124px) 100vw, 1124px\" \/>\n            <\/a>        <\/div>\n    <\/div>\n<\/article>            <\/div>\n                    <div class=\"col-md-6 col-lg-3 mb-5\">\n                <article class=\"member onScroll\">\n    <div class=\"member-asset\">\n        <div class=\"member-asset-inner\">\n            <a href=\"https:\/\/www.wisconsinports.com\/\" target=\"_blank\" class=\"member-link\">                <img loading=\"lazy\" decoding=\"async\" width=\"710\" height=\"258\" src=\"https:\/\/marinedelivers.com\/wp-content\/uploads\/2026\/02\/Wisconsin-Ports-Association.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/marinedelivers.com\/wp-content\/uploads\/2026\/02\/Wisconsin-Ports-Association.png 710w, https:\/\/marinedelivers.com\/wp-content\/uploads\/2026\/02\/Wisconsin-Ports-Association-300x109.png 300w\" sizes=\"auto, (max-width: 710px) 100vw, 710px\" \/>\n            <\/a>        <\/div>\n    <\/div>\n<\/article>            <\/div>\n        <\/div>\n\n    <\/div>\n    <\/div>\n\n\n\n<div style=\"height:89px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group alignwide mb-n-20 is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-text-align-center onScroll has-text-color\" style=\"color:#199dd9\">Vous souhaitez vous joindre \u00e0 nous ?<\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full shadow onScroll\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"513\" src=\"http:\/\/marinedelivers.com\/wp-content\/uploads\/2023\/07\/CEE-Terminal-Tower-copy-2-768x513-1.jpg\" alt=\"The Cleveland-Europe Express 2015: Port of Cleveland - Photo \u00a9 Bob Perkoski, www.Perkoski.com\" class=\"wp-image-120\" srcset=\"https:\/\/marinedelivers.com\/wp-content\/uploads\/2023\/07\/CEE-Terminal-Tower-copy-2-768x513-1.jpg 768w, https:\/\/marinedelivers.com\/wp-content\/uploads\/2023\/07\/CEE-Terminal-Tower-copy-2-768x513-1-300x200.jpg 300w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull bgLinesDark has-background is-layout-constrained wp-container-core-group-is-layout-2a7a16a9 wp-block-group-is-layout-constrained\" style=\"background-color:#0d223f;padding-top:20rem;padding-right:var(--wp--preset--spacing--30);padding-bottom:var(--wp--preset--spacing--70);padding-left:var(--wp--preset--spacing--30)\">\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div style=\"height:3vh\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center onScroll has-white-color has-text-color\" style=\"font-style:normal;font-weight:500\">En tant que seule organisation binationale de ce genre, nous repr\u00e9sentons, offrons une voix unifi\u00e9e et proposons des avantages uniques \u00e0 un large \u00e9ventail d\u2019intervenants de l\u2019industrie maritime.<\/h3>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button btn onScroll\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/marinedelivers.com\/fr\/adhesion\/\" target=\"_blank\" rel=\"noreferrer noopener\">En savoir plus sur l\u2019adh\u00e9sion<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Fond\u00e9e en 1959, la Chambre de commerce maritime relie la&#8230;<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4920","page","type-page","status-publish","hentry"],"acf":{"title_subheading":"","title_content":"","title_button":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nos membres - Chambre de Commerce Maritime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/marinedelivers.com\/fr\/nos-membres\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nos membres - Chambre de Commerce Maritime\" \/>\n<meta property=\"og:description\" content=\"Fond\u00e9e en 1959, la Chambre de commerce maritime relie la...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/marinedelivers.com\/fr\/nos-membres\/\" \/>\n<meta property=\"og:site_name\" content=\"Chambre de Commerce Maritime\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MarineDelivers\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-13T20:25:31+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/marinedelivers.com\/wp-content\/uploads\/2023\/07\/CEE-Terminal-Tower-copy-2-768x513-1.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@marinedelivers\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/marinedelivers.com\\\/fr\\\/nos-membres\\\/\",\"url\":\"https:\\\/\\\/marinedelivers.com\\\/fr\\\/nos-membres\\\/\",\"name\":\"Nos membres - Chambre de Commerce Maritime\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marinedelivers.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/marinedelivers.com\\\/fr\\\/nos-membres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/marinedelivers.com\\\/fr\\\/nos-membres\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/marinedelivers.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/CEE-Terminal-Tower-copy-2-768x513-1.jpg\",\"datePublished\":\"2023-07-18T20:54:14+00:00\",\"dateModified\":\"2026-08-13T20:25:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/marinedelivers.com\\\/fr\\\/nos-membres\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/marinedelivers.com\\\/fr\\\/nos-membres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/marinedelivers.com\\\/fr\\\/nos-membres\\\/#primaryimage\",\"url\":\"http:\\\/\\\/marinedelivers.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/CEE-Terminal-Tower-copy-2-768x513-1.jpg\",\"contentUrl\":\"http:\\\/\\\/marinedelivers.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/CEE-Terminal-Tower-copy-2-768x513-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/marinedelivers.com\\\/fr\\\/nos-membres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/marinedelivers.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nos membres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/marinedelivers.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/marinedelivers.com\\\/fr\\\/\",\"name\":\"Chambre de Commerce Maritime\",\"description\":\"Marine delivers our exports to the world\",\"publisher\":{\"@id\":\"https:\\\/\\\/marinedelivers.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/marinedelivers.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/marinedelivers.com\\\/fr\\\/#organization\",\"name\":\"Chamber of Marine Commerce\",\"url\":\"https:\\\/\\\/marinedelivers.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/marinedelivers.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/marinedelivers.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cmc-logo.svg\",\"contentUrl\":\"http:\\\/\\\/marinedelivers.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cmc-logo.svg\",\"width\":1,\"height\":1,\"caption\":\"Chamber of Marine Commerce\"},\"image\":{\"@id\":\"https:\\\/\\\/marinedelivers.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MarineDelivers\\\/\",\"https:\\\/\\\/x.com\\\/marinedelivers\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nos membres - Chambre de Commerce Maritime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/marinedelivers.com\/fr\/nos-membres\/","og_locale":"fr_FR","og_type":"article","og_title":"Nos membres - Chambre de Commerce Maritime","og_description":"Fond\u00e9e en 1959, la Chambre de commerce maritime relie la...","og_url":"https:\/\/marinedelivers.com\/fr\/nos-membres\/","og_site_name":"Chambre de Commerce Maritime","article_publisher":"https:\/\/www.facebook.com\/MarineDelivers\/","article_modified_time":"2026-08-13T20:25:31+00:00","og_image":[{"url":"http:\/\/marinedelivers.com\/wp-content\/uploads\/2023\/07\/CEE-Terminal-Tower-copy-2-768x513-1.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@marinedelivers","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/marinedelivers.com\/fr\/nos-membres\/","url":"https:\/\/marinedelivers.com\/fr\/nos-membres\/","name":"Nos membres - Chambre de Commerce Maritime","isPartOf":{"@id":"https:\/\/marinedelivers.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/marinedelivers.com\/fr\/nos-membres\/#primaryimage"},"image":{"@id":"https:\/\/marinedelivers.com\/fr\/nos-membres\/#primaryimage"},"thumbnailUrl":"http:\/\/marinedelivers.com\/wp-content\/uploads\/2023\/07\/CEE-Terminal-Tower-copy-2-768x513-1.jpg","datePublished":"2023-07-18T20:54:14+00:00","dateModified":"2026-08-13T20:25:31+00:00","breadcrumb":{"@id":"https:\/\/marinedelivers.com\/fr\/nos-membres\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/marinedelivers.com\/fr\/nos-membres\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/marinedelivers.com\/fr\/nos-membres\/#primaryimage","url":"http:\/\/marinedelivers.com\/wp-content\/uploads\/2023\/07\/CEE-Terminal-Tower-copy-2-768x513-1.jpg","contentUrl":"http:\/\/marinedelivers.com\/wp-content\/uploads\/2023\/07\/CEE-Terminal-Tower-copy-2-768x513-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/marinedelivers.com\/fr\/nos-membres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/marinedelivers.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Nos membres"}]},{"@type":"WebSite","@id":"https:\/\/marinedelivers.com\/fr\/#website","url":"https:\/\/marinedelivers.com\/fr\/","name":"Chambre de Commerce Maritime","description":"Marine delivers our exports to the world","publisher":{"@id":"https:\/\/marinedelivers.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/marinedelivers.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/marinedelivers.com\/fr\/#organization","name":"Chamber of Marine Commerce","url":"https:\/\/marinedelivers.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/marinedelivers.com\/fr\/#\/schema\/logo\/image\/","url":"http:\/\/marinedelivers.com\/wp-content\/uploads\/2023\/07\/cmc-logo.svg","contentUrl":"http:\/\/marinedelivers.com\/wp-content\/uploads\/2023\/07\/cmc-logo.svg","width":1,"height":1,"caption":"Chamber of Marine Commerce"},"image":{"@id":"https:\/\/marinedelivers.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MarineDelivers\/","https:\/\/x.com\/marinedelivers"]}]}},"_links":{"self":[{"href":"https:\/\/marinedelivers.com\/fr\/wp-json\/wp\/v2\/pages\/4920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marinedelivers.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/marinedelivers.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/marinedelivers.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/marinedelivers.com\/fr\/wp-json\/wp\/v2\/comments?post=4920"}],"version-history":[{"count":34,"href":"https:\/\/marinedelivers.com\/fr\/wp-json\/wp\/v2\/pages\/4920\/revisions"}],"predecessor-version":[{"id":6485,"href":"https:\/\/marinedelivers.com\/fr\/wp-json\/wp\/v2\/pages\/4920\/revisions\/6485"}],"wp:attachment":[{"href":"https:\/\/marinedelivers.com\/fr\/wp-json\/wp\/v2\/media?parent=4920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}